{"id":3895,"date":"2026-05-11T11:00:43","date_gmt":"2026-05-11T09:00:43","guid":{"rendered":"https:\/\/www.smeraldoterme.it\/?post_type=offer&#038;p=3895"},"modified":"2026-05-11T11:00:43","modified_gmt":"2026-05-11T09:00:43","slug":"maggio-rigenerante","status":"publish","type":"offer","link":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/","title":{"rendered":"MAGGIO RIGENERANTE"},"content":{"rendered":"<div  class=\"grids-section grids-is-advanced alignfull\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:2\/7;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<h2 class=\"wp-block-heading\">MAGGIO RIGENERANTE<\/h2>\n\n\n\n<p><strong>4 notti al prezzo di 3 | Mezza pensione<\/strong><br><strong>Una notte la offre la primavera<\/strong><br><br>Un soggiorno pensato per ritrovare energia e benessere, tra acque termali, relax e una pausa tutta per s\u00e9.<br><br><strong>A partire da:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u20ac277 per persona invece di \u20ac354<\/strong><\/li>\n\n\n\n<li>Supplemento massaggio da 50 minuti: + \u20ac22 per persona<\/li>\n<\/ul>\n\n\n\n<p><strong><strong>Il pacchetto include:<\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>4 notti<\/strong> in camera doppia Classic <strong>al prezzo di 3<\/strong><\/li>\n\n\n\n<li>Trattamento di <strong>mezza pensione<\/strong><\/li>\n\n\n\n<li><strong>Accesso alle piscine termali<\/strong><\/li>\n\n\n\n<li><strong>Kit SPA con accappatoio<\/strong><\/li>\n\n\n\n<li><strong>1 massaggio personalizzato<\/strong> da 25 minuti<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/booking.passepartout.cloud\/booking?oidPortale=15997&amp;lingua=it\" target=\"_blank\" rel=\"noreferrer noopener\">Richiedi disponibilit\u00e0<\/a><\/div>\n<\/div>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:8\/12;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1692\" src=\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp\" alt=\"\" class=\"wp-image-3892\" srcset=\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp 2560w, https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-300x198.webp 300w, https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-1024x677.webp 1024w, https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-768x508.webp 768w, https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-1536x1015.webp 1536w, https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-2048x1354.webp 2048w, https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-1568x1036.webp 1568w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>4 notti al prezzo di 3, per vivere una pausa rigenerante tra acque termali, benessere e profumo di primavera.<\/p>\n","protected":false},"author":15,"featured_media":3892,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"offer_categories":[53],"class_list":["post-3895","offer","type-offer","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MAGGIO RIGENERANTE - Hotel Smeraldo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAGGIO RIGENERANTE - Hotel Smeraldo\" \/>\n<meta property=\"og:description\" content=\"4 notti al prezzo di 3, per vivere una pausa rigenerante tra acque termali, benessere e profumo di primavera.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Smeraldo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/\",\"url\":\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/\",\"name\":\"MAGGIO RIGENERANTE - Hotel Smeraldo\",\"isPartOf\":{\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp\",\"datePublished\":\"2026-05-11T09:00:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#primaryimage\",\"url\":\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp\",\"contentUrl\":\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp\",\"width\":2560,\"height\":1692},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.smeraldoterme.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MAGGIO RIGENERANTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/#website\",\"url\":\"https:\/\/www.smeraldoterme.it\/it\/\",\"name\":\"Hotel Smeraldo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.smeraldoterme.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/#organization\",\"name\":\"Hotel Smeraldo\",\"url\":\"https:\/\/www.smeraldoterme.it\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2022\/11\/logo-hotel-smeraldo.png\",\"contentUrl\":\"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2022\/11\/logo-hotel-smeraldo.png\",\"width\":400,\"height\":114,\"caption\":\"Hotel Smeraldo\"},\"image\":{\"@id\":\"https:\/\/www.smeraldoterme.it\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGGIO RIGENERANTE - Hotel Smeraldo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/","og_locale":"it_IT","og_type":"article","og_title":"MAGGIO RIGENERANTE - Hotel Smeraldo","og_description":"4 notti al prezzo di 3, per vivere una pausa rigenerante tra acque termali, benessere e profumo di primavera.","og_url":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/","og_site_name":"Hotel Smeraldo","og_image":[{"width":2560,"height":1692,"url":"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/","url":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/","name":"MAGGIO RIGENERANTE - Hotel Smeraldo","isPartOf":{"@id":"https:\/\/www.smeraldoterme.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#primaryimage"},"image":{"@id":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp","datePublished":"2026-05-11T09:00:43+00:00","breadcrumb":{"@id":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#primaryimage","url":"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp","contentUrl":"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-scaled.webp","width":2560,"height":1692},{"@type":"BreadcrumbList","@id":"https:\/\/www.smeraldoterme.it\/it\/offerta\/maggio-rigenerante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smeraldoterme.it\/it\/"},{"@type":"ListItem","position":2,"name":"MAGGIO RIGENERANTE"}]},{"@type":"WebSite","@id":"https:\/\/www.smeraldoterme.it\/it\/#website","url":"https:\/\/www.smeraldoterme.it\/it\/","name":"Hotel Smeraldo","description":"","publisher":{"@id":"https:\/\/www.smeraldoterme.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smeraldoterme.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.smeraldoterme.it\/it\/#organization","name":"Hotel Smeraldo","url":"https:\/\/www.smeraldoterme.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smeraldoterme.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2022\/11\/logo-hotel-smeraldo.png","contentUrl":"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2022\/11\/logo-hotel-smeraldo.png","width":400,"height":114,"caption":"Hotel Smeraldo"},"image":{"@id":"https:\/\/www.smeraldoterme.it\/it\/#\/schema\/logo\/image\/"}}]}},"featured_img":"https:\/\/www.smeraldoterme.it\/wp-content\/uploads\/2026\/05\/maggio-rigenerante-1568x1036.webp","coauthors":[],"author_meta":{"author_link":"https:\/\/www.smeraldoterme.it\/it\/author\/mattia-a\/","display_name":"Mattia A."},"relative_dates":{"created":"Pubblicato 2 giorni fa","modified":"Aggiornato 2 giorni fa"},"absolute_dates":{"created":"Pubblicato il Maggio 11, 2026","modified":"Aggiornato il Maggio 11, 2026"},"absolute_dates_time":{"created":"Pubblicato il Maggio 11, 2026 11:00 am","modified":"Aggiornato il Maggio 11, 2026 11:00 am"},"featured_img_caption":"","tax_additional":{"offer_categories":{"linked":["<a href=\"https:\/\/www.smeraldoterme.it\/it\/offer_categories\/maggio\/\" class=\"advgb-post-tax-term\">MAGGIO<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">MAGGIO<\/span>"],"slug":"offer_categories","name":"Categorie"},"translation_priority":{"linked":["<a href=\"https:\/\/www.smeraldoterme.it\/it\/?taxonomy=translation_priority&#038;term=optional-2\" class=\"advgb-post-tax-term\">Optional<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Optional<\/span>"],"slug":"translation_priority","name":"Priorit\u00e0 di Traduzione"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/offer\/3895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/offer"}],"about":[{"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/types\/offer"}],"author":[{"embeddable":true,"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/users\/15"}],"version-history":[{"count":6,"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/offer\/3895\/revisions"}],"predecessor-version":[{"id":3918,"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/offer\/3895\/revisions\/3918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/media\/3892"}],"wp:attachment":[{"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/media?parent=3895"}],"wp:term":[{"taxonomy":"offer_categories","embeddable":true,"href":"https:\/\/www.smeraldoterme.it\/it\/wp-json\/wp\/v2\/offer_categories?post=3895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}